{"id":2011,"date":"2025-08-25T17:59:45","date_gmt":"2025-08-25T15:59:45","guid":{"rendered":"https:\/\/www.kanziapple.com\/receptai\/"},"modified":"2025-11-06T16:39:07","modified_gmt":"2025-11-06T15:39:07","slug":"receptai","status":"publish","type":"page","link":"https:\/\/www.kanziapple.com\/lt\/receptai\/","title":{"rendered":"Receptai"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2011\" class=\"elementor elementor-2011 elementor-502\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0ea3d06 e-con-full e-flex e-con e-parent\" data-id=\"0ea3d06\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0f0d55c e-grid e-con-full e-con e-child\" data-id=\"0f0d55c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1b047b1 e-con-full e-flex e-con e-child\" data-id=\"1b047b1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b27a09 elementor-widget elementor-widget-heading\" data-id=\"5b27a09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Skanu. \u0160vie\u017eia. Ir suteikia j\u0117g\u0173.  <\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcb8c35 elementor-widget elementor-widget-text-editor\" data-id=\"bcb8c35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tKANZI\u00ae receptai \u2013 tai dr\u0105s\u016bs skoni\u0173 deriniai be r\u016bpes\u010di\u0173. Greita, \u0161vie\u017eia ir gardu \u2013 sukurta j\u016bs\u0173 dienai. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56b58e9 elementor-widget elementor-widget-image\" data-id=\"56b58e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"749\" src=\"https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/09\/kanzi-recipe_background.webp\" class=\"attachment-large size-large wp-image-2010\" alt=\"Kanzi receptas fonas\" srcset=\"https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/09\/kanzi-recipe_background.webp 849w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/09\/kanzi-recipe_background-300x281.webp 300w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/09\/kanzi-recipe_background-768x719.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a6b9387 e-con-full e-flex e-con e-parent\" data-id=\"a6b9387\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-176dc98 elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"176dc98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/09\/kanzi_divider.svg\" class=\"attachment-large size-large wp-image-1994\" alt=\"Kanzi skirstytuvas\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f82075 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"1f82075\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/09\/kanzi-divider.svg\" class=\"attachment-large size-large wp-image-1995\" alt=\"Kanzi skirstytuvas\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-967afed e-flex e-con-boxed e-con e-parent\" data-id=\"967afed\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ec90cb elementor-grid-1 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-loop-grid\" data-id=\"4ec90cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:733,&quot;columns&quot;:1,&quot;pagination_type&quot;:&quot;numbers&quot;,&quot;_skin&quot;:&quot;post&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;[data-elementor-type=\\&quot;loop-item\\&quot;]&quot;,&quot;pagination_load_type&quot;:&quot;page_reload&quot;,&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-grid.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-loop-nothing-found-message\">\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5171ac8 e-flex e-con-boxed e-con e-parent\" data-id=\"5171ac8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-293066d e-con-full e-flex e-con e-child\" data-id=\"293066d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fa0fc10 elementor-widget elementor-widget-heading\" data-id=\"fa0fc10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">J\u0116G\u0172 SUTEIKIANTYS RECEPTAI<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b33e08c elementor-widget elementor-widget-text-editor\" data-id=\"b33e08c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-sheets-root=\"1\">KANZI\u00ae sezonas su m\u016bs\u0173 kruop\u0161\u010diai atrinktais receptais \u2013 saldu, gaivu, visada tra\u0161ku. Nuo greit\u0173 u\u017ekand\u017ei\u0173 iki i\u0161skirtini\u0173 patiekal\u0173 \u2013 id\u0117jos, kurios tiks j\u016bs\u0173 dienai ir nustebins skoniu. Receptus nuolat papildome. Gr\u012f\u017ekite alkani \u2013 visada rasite k\u0105 nors naujo i\u0161bandyti.\u0160tai kas KANZI\u00ae sezono metu: rankomis atrinkti dr\u0105siausi m\u016bs\u0173 receptai &#8211; sald\u016bs, pikanti\u0161ki, visada pilni tra\u0161kumo. Nuo greit\u0173 u\u017ekand\u017ei\u0173 iki i\u0161skirtini\u0173 pagrindini\u0173 patiekal\u0173 &#8211; \u0161ios id\u0117jos pritaikytos j\u016bs\u0173 dienai ir nustebins j\u016bs\u0173 skonio receptorius. Ir nuolat pridedame daugiau. Gr\u012f\u017ekite alkani &#8211; visada rasite k\u0105 nors naujo i\u0161bandyti.   <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b26018 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-loop-grid\" data-id=\"8b26018\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:556,&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:24,&quot;sizes&quot;:[]},&quot;pagination_type&quot;:&quot;load_more_infinite_scroll&quot;,&quot;_skin&quot;:&quot;post&quot;,&quot;columns&quot;:&quot;3&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;[data-elementor-type=\\&quot;loop-item\\&quot;]&quot;,&quot;load_more_spinner&quot;:{&quot;value&quot;:&quot;fas fa-spinner&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-grid.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-loop-container elementor-grid\" role=\"list\">\n\t\t<style id=\"loop-556\">.elementor-556 .elementor-element.elementor-element-fc23f9e{--display:flex;--gap:16px 16px;--row-gap:16px;--column-gap:16px;}.elementor-556 .elementor-element.elementor-element-67898cc img{width:100%;height:400px;object-fit:cover;object-position:center center;border-style:none;border-radius:20px 20px 20px 20px;}.elementor-556 .elementor-element.elementor-element-becb9d1{--display:flex;--gap:8px 8px;--row-gap:8px;--column-gap:8px;}.elementor-556 .elementor-element.elementor-element-b8199d6 .elementor-heading-title{font-family:var( --e-global-typography-80a0c69-font-family ), Sans-serif;font-size:var( --e-global-typography-80a0c69-font-size );font-weight:var( --e-global-typography-80a0c69-font-weight );text-transform:var( --e-global-typography-80a0c69-text-transform );line-height:var( --e-global-typography-80a0c69-line-height );letter-spacing:var( --e-global-typography-80a0c69-letter-spacing );word-spacing:var( --e-global-typography-80a0c69-word-spacing );}.elementor-556 .elementor-element.elementor-element-b94addd .elementor-icon-list-icon i{color:var( --e-global-color-text );transition:color 0.3s;}.elementor-556 .elementor-element.elementor-element-b94addd .elementor-icon-list-icon svg{fill:var( --e-global-color-text );transition:fill 0.3s;}.elementor-556 .elementor-element.elementor-element-b94addd{--e-icon-list-icon-size:18px;--e-icon-list-icon-align:center;--e-icon-list-icon-margin:0 calc(var(--e-icon-list-icon-size, 1em) * 0.125);--icon-vertical-align:center;--icon-vertical-offset:1px;}.elementor-556 .elementor-element.elementor-element-b94addd .elementor-icon-list-icon{padding-inline-end:0px;}.elementor-556 .elementor-element.elementor-element-b94addd .elementor-icon-list-item > .elementor-icon-list-text, .elementor-556 .elementor-element.elementor-element-b94addd .elementor-icon-list-item > a{font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-size:var( --e-global-typography-text-font-size );font-weight:var( --e-global-typography-text-font-weight );line-height:var( --e-global-typography-text-line-height );letter-spacing:var( --e-global-typography-text-letter-spacing );}.elementor-556 .elementor-element.elementor-element-b94addd .elementor-icon-list-text{color:var( --e-global-color-435f1d4 );transition:color 0.3s;}.elementor-556 .elementor-element.elementor-element-b94addd .elementor-icon-list-item:hover .elementor-icon-list-text{color:var( --e-global-color-435f1d4 );}.elementor-556 .elementor-element.elementor-element-b94addd.elementor-element{--flex-grow:0;--flex-shrink:0;}@media(max-width:1024px){.elementor-556 .elementor-element.elementor-element-fc23f9e{--align-items:stretch;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );}.elementor-556 .elementor-element.elementor-element-67898cc img{width:100%;}.elementor-556 .elementor-element.elementor-element-b8199d6 .elementor-heading-title{font-size:var( --e-global-typography-80a0c69-font-size );line-height:var( --e-global-typography-80a0c69-line-height );letter-spacing:var( --e-global-typography-80a0c69-letter-spacing );word-spacing:var( --e-global-typography-80a0c69-word-spacing );}.elementor-556 .elementor-element.elementor-element-b94addd .elementor-icon-list-item > .elementor-icon-list-text, .elementor-556 .elementor-element.elementor-element-b94addd .elementor-icon-list-item > a{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );letter-spacing:var( --e-global-typography-text-letter-spacing );}}@media(max-width:1024px) and (min-width:768px){.elementor-556 .elementor-element.elementor-element-fc23f9e{--content-width:100%;}}@media(max-width:767px){.elementor-556 .elementor-element.elementor-element-fc23f9e{--content-width:100%;}.elementor-556 .elementor-element.elementor-element-b8199d6 .elementor-heading-title{font-size:var( --e-global-typography-80a0c69-font-size );line-height:var( --e-global-typography-80a0c69-line-height );letter-spacing:var( --e-global-typography-80a0c69-letter-spacing );word-spacing:var( --e-global-typography-80a0c69-word-spacing );}.elementor-556 .elementor-element.elementor-element-b94addd .elementor-icon-list-item > .elementor-icon-list-text, .elementor-556 .elementor-element.elementor-element-b94addd .elementor-icon-list-item > a{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );letter-spacing:var( --e-global-typography-text-letter-spacing );}}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"556\" class=\"elementor elementor-556 e-loop-item e-loop-item-2177 post-2177 recipe type-recipe status-publish has-post-thumbnail hentry\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-fc23f9e e-flex e-con-boxed e-con e-parent\" data-id=\"fc23f9e\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/www.kanziapple.com\/lt\/recipe\/obuoliu-pyragas\/\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-67898cc elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"67898cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Zicca-pirukas-1024x1024.jpg\" class=\"attachment-large size-large wp-image-2176\" alt=\"\" srcset=\"https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Zicca-pirukas-1024x1024.jpg 1024w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Zicca-pirukas-300x300.jpg 300w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Zicca-pirukas-150x150.jpg 150w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Zicca-pirukas-768x768.jpg 768w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Zicca-pirukas-1536x1536.jpg 1536w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Zicca-pirukas-2048x2048.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-becb9d1 e-con-full e-flex e-con e-child\" data-id=\"becb9d1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b8199d6 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"b8199d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">OBUOLI\u0172 PYRAGAS<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b94addd elementor-icon-list--layout-inline elementor-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b94addd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\" viewBox=\"0 0 18 18\" fill=\"none\"><g clip-path=\"url(#clip0_505_523)\"><path d=\"M15.9336 12.6309C16.3478 12.6309 16.6836 12.2951 16.6836 11.8809C16.6836 11.4666 16.3478 11.1309 15.9336 11.1309C15.5194 11.1309 15.1836 11.4666 15.1836 11.8809C15.1836 12.2951 15.5194 12.6309 15.9336 12.6309Z\" fill=\"white\"><\/path><path d=\"M14.2979 15.0469C14.7121 15.0469 15.0479 14.7111 15.0479 14.2969C15.0479 13.8827 14.7121 13.5469 14.2979 13.5469C13.8836 13.5469 13.5479 13.8827 13.5479 14.2969C13.5479 14.7111 13.8836 15.0469 14.2979 15.0469Z\" fill=\"white\"><\/path><path d=\"M16.4971 9.75391C16.9113 9.75391 17.2471 9.41812 17.2471 9.00391C17.2471 8.58969 16.9113 8.25391 16.4971 8.25391C16.0829 8.25391 15.7471 8.58969 15.7471 9.00391C15.7471 9.41812 16.0829 9.75391 16.4971 9.75391Z\" fill=\"white\"><\/path><path d=\"M11.8682 16.6855C12.2824 16.6855 12.6182 16.3498 12.6182 15.9355C12.6182 15.5213 12.2824 15.1855 11.8682 15.1855C11.454 15.1855 11.1182 15.5213 11.1182 15.9355C11.1182 16.3498 11.454 16.6855 11.8682 16.6855Z\" fill=\"white\"><\/path><path d=\"M8.99963 15.75C7.91942 15.7513 6.85467 15.4933 5.89484 14.9978C4.93501 14.5022 4.10813 13.7835 3.48367 12.9021C2.85921 12.0207 2.45541 11.0023 2.3062 9.9324C2.15699 8.86254 2.26672 7.77249 2.62618 6.75384C2.98563 5.73519 3.58432 4.81769 4.37193 4.07841C5.15954 3.33913 6.11307 2.79968 7.15242 2.50537C8.19176 2.21106 9.28656 2.17049 10.3448 2.38707C11.4031 2.60364 12.394 3.07104 13.2341 3.75H11.9996C11.8007 3.75 11.61 3.82902 11.4693 3.96967C11.3286 4.11032 11.2496 4.30109 11.2496 4.5C11.2496 4.69891 11.3286 4.88968 11.4693 5.03033C11.61 5.17098 11.8007 5.25 11.9996 5.25H14.9996C15.1985 5.25 15.3893 5.17098 15.53 5.03033C15.6706 4.88968 15.7496 4.69891 15.7496 4.5V1.5C15.7496 1.30109 15.6706 1.11032 15.53 0.96967C15.3893 0.829018 15.1985 0.75 14.9996 0.75C14.8007 0.75 14.61 0.829018 14.4693 0.96967C14.3286 1.11032 14.2496 1.30109 14.2496 1.5V2.64825C13.2297 1.80506 12.0219 1.2197 10.7281 0.941625C9.43436 0.663547 8.09267 0.700915 6.81638 1.05057C5.5401 1.40023 4.36671 2.05191 3.39532 2.95056C2.42394 3.84921 1.68309 4.96843 1.23536 6.2137C0.787628 7.45897 0.646162 8.79371 0.822912 10.1052C0.999661 11.4166 1.48943 12.6663 2.25086 13.7486C3.01229 14.8309 4.023 15.7141 5.19764 16.3235C6.37227 16.9329 7.67632 17.2507 8.99963 17.25C9.19854 17.25 9.38931 17.171 9.52996 17.0303C9.67061 16.8897 9.74963 16.6989 9.74963 16.5C9.74963 16.3011 9.67061 16.1103 9.52996 15.9697C9.38931 15.829 9.19854 15.75 8.99963 15.75Z\" fill=\"white\"><\/path><path d=\"M11.7802 11.7802C11.9209 11.6396 11.9998 11.4489 11.9998 11.25C11.9998 11.0511 11.9209 10.8604 11.7802 10.7198L9.75 8.6895V4.5C9.75 4.30109 9.67098 4.11032 9.53033 3.96967C9.38968 3.82902 9.19891 3.75 9 3.75C8.80109 3.75 8.61032 3.82902 8.46967 3.96967C8.32902 4.11032 8.25 4.30109 8.25 4.5V9C8.25004 9.1989 8.32909 9.38963 8.46975 9.53025L10.7198 11.7802C10.8604 11.9209 11.0511 11.9998 11.25 11.9998C11.4489 11.9998 11.6396 11.9209 11.7802 11.7802Z\" fill=\"white\"><\/path><\/g><defs><clipPath id=\"clip0_505_523\"><rect width=\"18\" height=\"18\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">50 mins<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"556\" class=\"elementor elementor-556 e-loop-item e-loop-item-2171 post-2171 recipe type-recipe status-publish has-post-thumbnail hentry\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-fc23f9e e-flex e-con-boxed e-con e-parent\" data-id=\"fc23f9e\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/www.kanziapple.com\/lt\/recipe\/sulauzytu-obuoliu-desertas-su-vaniliniu-jogurtu\/\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-67898cc elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"67898cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Purune-ounadessert-vaniljejogurtiga-1024x1024.jpg\" class=\"attachment-large size-large wp-image-2169\" alt=\"\" srcset=\"https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Purune-ounadessert-vaniljejogurtiga-1024x1024.jpg 1024w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Purune-ounadessert-vaniljejogurtiga-300x300.jpg 300w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Purune-ounadessert-vaniljejogurtiga-150x150.jpg 150w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Purune-ounadessert-vaniljejogurtiga-768x768.jpg 768w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Purune-ounadessert-vaniljejogurtiga-1536x1536.jpg 1536w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Purune-ounadessert-vaniljejogurtiga-2048x2048.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-becb9d1 e-con-full e-flex e-con e-child\" data-id=\"becb9d1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b8199d6 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"b8199d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">TRUPININIS PYRAGAS SU OBUOLIAIS IR VANILINIU JOGURTU<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b94addd elementor-icon-list--layout-inline elementor-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b94addd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\" viewBox=\"0 0 18 18\" fill=\"none\"><g clip-path=\"url(#clip0_505_523)\"><path d=\"M15.9336 12.6309C16.3478 12.6309 16.6836 12.2951 16.6836 11.8809C16.6836 11.4666 16.3478 11.1309 15.9336 11.1309C15.5194 11.1309 15.1836 11.4666 15.1836 11.8809C15.1836 12.2951 15.5194 12.6309 15.9336 12.6309Z\" fill=\"white\"><\/path><path d=\"M14.2979 15.0469C14.7121 15.0469 15.0479 14.7111 15.0479 14.2969C15.0479 13.8827 14.7121 13.5469 14.2979 13.5469C13.8836 13.5469 13.5479 13.8827 13.5479 14.2969C13.5479 14.7111 13.8836 15.0469 14.2979 15.0469Z\" fill=\"white\"><\/path><path d=\"M16.4971 9.75391C16.9113 9.75391 17.2471 9.41812 17.2471 9.00391C17.2471 8.58969 16.9113 8.25391 16.4971 8.25391C16.0829 8.25391 15.7471 8.58969 15.7471 9.00391C15.7471 9.41812 16.0829 9.75391 16.4971 9.75391Z\" fill=\"white\"><\/path><path d=\"M11.8682 16.6855C12.2824 16.6855 12.6182 16.3498 12.6182 15.9355C12.6182 15.5213 12.2824 15.1855 11.8682 15.1855C11.454 15.1855 11.1182 15.5213 11.1182 15.9355C11.1182 16.3498 11.454 16.6855 11.8682 16.6855Z\" fill=\"white\"><\/path><path d=\"M8.99963 15.75C7.91942 15.7513 6.85467 15.4933 5.89484 14.9978C4.93501 14.5022 4.10813 13.7835 3.48367 12.9021C2.85921 12.0207 2.45541 11.0023 2.3062 9.9324C2.15699 8.86254 2.26672 7.77249 2.62618 6.75384C2.98563 5.73519 3.58432 4.81769 4.37193 4.07841C5.15954 3.33913 6.11307 2.79968 7.15242 2.50537C8.19176 2.21106 9.28656 2.17049 10.3448 2.38707C11.4031 2.60364 12.394 3.07104 13.2341 3.75H11.9996C11.8007 3.75 11.61 3.82902 11.4693 3.96967C11.3286 4.11032 11.2496 4.30109 11.2496 4.5C11.2496 4.69891 11.3286 4.88968 11.4693 5.03033C11.61 5.17098 11.8007 5.25 11.9996 5.25H14.9996C15.1985 5.25 15.3893 5.17098 15.53 5.03033C15.6706 4.88968 15.7496 4.69891 15.7496 4.5V1.5C15.7496 1.30109 15.6706 1.11032 15.53 0.96967C15.3893 0.829018 15.1985 0.75 14.9996 0.75C14.8007 0.75 14.61 0.829018 14.4693 0.96967C14.3286 1.11032 14.2496 1.30109 14.2496 1.5V2.64825C13.2297 1.80506 12.0219 1.2197 10.7281 0.941625C9.43436 0.663547 8.09267 0.700915 6.81638 1.05057C5.5401 1.40023 4.36671 2.05191 3.39532 2.95056C2.42394 3.84921 1.68309 4.96843 1.23536 6.2137C0.787628 7.45897 0.646162 8.79371 0.822912 10.1052C0.999661 11.4166 1.48943 12.6663 2.25086 13.7486C3.01229 14.8309 4.023 15.7141 5.19764 16.3235C6.37227 16.9329 7.67632 17.2507 8.99963 17.25C9.19854 17.25 9.38931 17.171 9.52996 17.0303C9.67061 16.8897 9.74963 16.6989 9.74963 16.5C9.74963 16.3011 9.67061 16.1103 9.52996 15.9697C9.38931 15.829 9.19854 15.75 8.99963 15.75Z\" fill=\"white\"><\/path><path d=\"M11.7802 11.7802C11.9209 11.6396 11.9998 11.4489 11.9998 11.25C11.9998 11.0511 11.9209 10.8604 11.7802 10.7198L9.75 8.6895V4.5C9.75 4.30109 9.67098 4.11032 9.53033 3.96967C9.38968 3.82902 9.19891 3.75 9 3.75C8.80109 3.75 8.61032 3.82902 8.46967 3.96967C8.32902 4.11032 8.25 4.30109 8.25 4.5V9C8.25004 9.1989 8.32909 9.38963 8.46975 9.53025L10.7198 11.7802C10.8604 11.9209 11.0511 11.9998 11.25 11.9998C11.4489 11.9998 11.6396 11.9209 11.7802 11.7802Z\" fill=\"white\"><\/path><\/g><defs><clipPath id=\"clip0_505_523\"><rect width=\"18\" height=\"18\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">25 mins<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"556\" class=\"elementor elementor-556 e-loop-item e-loop-item-2165 post-2165 recipe type-recipe status-publish has-post-thumbnail hentry\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-fc23f9e e-flex e-con-boxed e-con e-parent\" data-id=\"fc23f9e\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/www.kanziapple.com\/lt\/recipe\/mesainiai-su-obuoliais\/\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-67898cc elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"67898cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Ounaburger-1024x1024.jpg\" class=\"attachment-large size-large wp-image-2164\" alt=\"\" srcset=\"https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Ounaburger-1024x1024.jpg 1024w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Ounaburger-300x300.jpg 300w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Ounaburger-150x150.jpg 150w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Ounaburger-768x768.jpg 768w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Ounaburger-1536x1536.jpg 1536w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Ounaburger-2048x2048.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-becb9d1 e-con-full e-flex e-con e-child\" data-id=\"becb9d1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b8199d6 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"b8199d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">M\u0116SAINIAI SU OBUOLIAIS<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b94addd elementor-icon-list--layout-inline elementor-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b94addd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\" viewBox=\"0 0 18 18\" fill=\"none\"><g clip-path=\"url(#clip0_505_523)\"><path d=\"M15.9336 12.6309C16.3478 12.6309 16.6836 12.2951 16.6836 11.8809C16.6836 11.4666 16.3478 11.1309 15.9336 11.1309C15.5194 11.1309 15.1836 11.4666 15.1836 11.8809C15.1836 12.2951 15.5194 12.6309 15.9336 12.6309Z\" fill=\"white\"><\/path><path d=\"M14.2979 15.0469C14.7121 15.0469 15.0479 14.7111 15.0479 14.2969C15.0479 13.8827 14.7121 13.5469 14.2979 13.5469C13.8836 13.5469 13.5479 13.8827 13.5479 14.2969C13.5479 14.7111 13.8836 15.0469 14.2979 15.0469Z\" fill=\"white\"><\/path><path d=\"M16.4971 9.75391C16.9113 9.75391 17.2471 9.41812 17.2471 9.00391C17.2471 8.58969 16.9113 8.25391 16.4971 8.25391C16.0829 8.25391 15.7471 8.58969 15.7471 9.00391C15.7471 9.41812 16.0829 9.75391 16.4971 9.75391Z\" fill=\"white\"><\/path><path d=\"M11.8682 16.6855C12.2824 16.6855 12.6182 16.3498 12.6182 15.9355C12.6182 15.5213 12.2824 15.1855 11.8682 15.1855C11.454 15.1855 11.1182 15.5213 11.1182 15.9355C11.1182 16.3498 11.454 16.6855 11.8682 16.6855Z\" fill=\"white\"><\/path><path d=\"M8.99963 15.75C7.91942 15.7513 6.85467 15.4933 5.89484 14.9978C4.93501 14.5022 4.10813 13.7835 3.48367 12.9021C2.85921 12.0207 2.45541 11.0023 2.3062 9.9324C2.15699 8.86254 2.26672 7.77249 2.62618 6.75384C2.98563 5.73519 3.58432 4.81769 4.37193 4.07841C5.15954 3.33913 6.11307 2.79968 7.15242 2.50537C8.19176 2.21106 9.28656 2.17049 10.3448 2.38707C11.4031 2.60364 12.394 3.07104 13.2341 3.75H11.9996C11.8007 3.75 11.61 3.82902 11.4693 3.96967C11.3286 4.11032 11.2496 4.30109 11.2496 4.5C11.2496 4.69891 11.3286 4.88968 11.4693 5.03033C11.61 5.17098 11.8007 5.25 11.9996 5.25H14.9996C15.1985 5.25 15.3893 5.17098 15.53 5.03033C15.6706 4.88968 15.7496 4.69891 15.7496 4.5V1.5C15.7496 1.30109 15.6706 1.11032 15.53 0.96967C15.3893 0.829018 15.1985 0.75 14.9996 0.75C14.8007 0.75 14.61 0.829018 14.4693 0.96967C14.3286 1.11032 14.2496 1.30109 14.2496 1.5V2.64825C13.2297 1.80506 12.0219 1.2197 10.7281 0.941625C9.43436 0.663547 8.09267 0.700915 6.81638 1.05057C5.5401 1.40023 4.36671 2.05191 3.39532 2.95056C2.42394 3.84921 1.68309 4.96843 1.23536 6.2137C0.787628 7.45897 0.646162 8.79371 0.822912 10.1052C0.999661 11.4166 1.48943 12.6663 2.25086 13.7486C3.01229 14.8309 4.023 15.7141 5.19764 16.3235C6.37227 16.9329 7.67632 17.2507 8.99963 17.25C9.19854 17.25 9.38931 17.171 9.52996 17.0303C9.67061 16.8897 9.74963 16.6989 9.74963 16.5C9.74963 16.3011 9.67061 16.1103 9.52996 15.9697C9.38931 15.829 9.19854 15.75 8.99963 15.75Z\" fill=\"white\"><\/path><path d=\"M11.7802 11.7802C11.9209 11.6396 11.9998 11.4489 11.9998 11.25C11.9998 11.0511 11.9209 10.8604 11.7802 10.7198L9.75 8.6895V4.5C9.75 4.30109 9.67098 4.11032 9.53033 3.96967C9.38968 3.82902 9.19891 3.75 9 3.75C8.80109 3.75 8.61032 3.82902 8.46967 3.96967C8.32902 4.11032 8.25 4.30109 8.25 4.5V9C8.25004 9.1989 8.32909 9.38963 8.46975 9.53025L10.7198 11.7802C10.8604 11.9209 11.0511 11.9998 11.25 11.9998C11.4489 11.9998 11.6396 11.9209 11.7802 11.7802Z\" fill=\"white\"><\/path><\/g><defs><clipPath id=\"clip0_505_523\"><rect width=\"18\" height=\"18\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">25 mins<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"556\" class=\"elementor elementor-556 e-loop-item e-loop-item-2159 post-2159 recipe type-recipe status-publish has-post-thumbnail hentry\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-fc23f9e e-flex e-con-boxed e-con e-parent\" data-id=\"fc23f9e\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/www.kanziapple.com\/lt\/recipe\/obuoliu-spinatu-salotos-su-siltu-ozkos-suriu\/\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-67898cc elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"67898cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Ouna-spinatisalat-ja-soe-kitsejuust1-1024x1024.jpg\" class=\"attachment-large size-large wp-image-2157\" alt=\"\" srcset=\"https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Ouna-spinatisalat-ja-soe-kitsejuust1-1024x1024.jpg 1024w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Ouna-spinatisalat-ja-soe-kitsejuust1-300x300.jpg 300w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Ouna-spinatisalat-ja-soe-kitsejuust1-150x150.jpg 150w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Ouna-spinatisalat-ja-soe-kitsejuust1-768x768.jpg 768w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Ouna-spinatisalat-ja-soe-kitsejuust1-1536x1536.jpg 1536w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Ouna-spinatisalat-ja-soe-kitsejuust1-2048x2048.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-becb9d1 e-con-full e-flex e-con e-child\" data-id=\"becb9d1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b8199d6 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"b8199d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">OBUOLI\u0172\u2013\u0160PINAT\u0172 SALOTOS SU \u0160ILTU O\u017dKOS S\u016aRIU<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b94addd elementor-icon-list--layout-inline elementor-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b94addd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\" viewBox=\"0 0 18 18\" fill=\"none\"><g clip-path=\"url(#clip0_505_523)\"><path d=\"M15.9336 12.6309C16.3478 12.6309 16.6836 12.2951 16.6836 11.8809C16.6836 11.4666 16.3478 11.1309 15.9336 11.1309C15.5194 11.1309 15.1836 11.4666 15.1836 11.8809C15.1836 12.2951 15.5194 12.6309 15.9336 12.6309Z\" fill=\"white\"><\/path><path d=\"M14.2979 15.0469C14.7121 15.0469 15.0479 14.7111 15.0479 14.2969C15.0479 13.8827 14.7121 13.5469 14.2979 13.5469C13.8836 13.5469 13.5479 13.8827 13.5479 14.2969C13.5479 14.7111 13.8836 15.0469 14.2979 15.0469Z\" fill=\"white\"><\/path><path d=\"M16.4971 9.75391C16.9113 9.75391 17.2471 9.41812 17.2471 9.00391C17.2471 8.58969 16.9113 8.25391 16.4971 8.25391C16.0829 8.25391 15.7471 8.58969 15.7471 9.00391C15.7471 9.41812 16.0829 9.75391 16.4971 9.75391Z\" fill=\"white\"><\/path><path d=\"M11.8682 16.6855C12.2824 16.6855 12.6182 16.3498 12.6182 15.9355C12.6182 15.5213 12.2824 15.1855 11.8682 15.1855C11.454 15.1855 11.1182 15.5213 11.1182 15.9355C11.1182 16.3498 11.454 16.6855 11.8682 16.6855Z\" fill=\"white\"><\/path><path d=\"M8.99963 15.75C7.91942 15.7513 6.85467 15.4933 5.89484 14.9978C4.93501 14.5022 4.10813 13.7835 3.48367 12.9021C2.85921 12.0207 2.45541 11.0023 2.3062 9.9324C2.15699 8.86254 2.26672 7.77249 2.62618 6.75384C2.98563 5.73519 3.58432 4.81769 4.37193 4.07841C5.15954 3.33913 6.11307 2.79968 7.15242 2.50537C8.19176 2.21106 9.28656 2.17049 10.3448 2.38707C11.4031 2.60364 12.394 3.07104 13.2341 3.75H11.9996C11.8007 3.75 11.61 3.82902 11.4693 3.96967C11.3286 4.11032 11.2496 4.30109 11.2496 4.5C11.2496 4.69891 11.3286 4.88968 11.4693 5.03033C11.61 5.17098 11.8007 5.25 11.9996 5.25H14.9996C15.1985 5.25 15.3893 5.17098 15.53 5.03033C15.6706 4.88968 15.7496 4.69891 15.7496 4.5V1.5C15.7496 1.30109 15.6706 1.11032 15.53 0.96967C15.3893 0.829018 15.1985 0.75 14.9996 0.75C14.8007 0.75 14.61 0.829018 14.4693 0.96967C14.3286 1.11032 14.2496 1.30109 14.2496 1.5V2.64825C13.2297 1.80506 12.0219 1.2197 10.7281 0.941625C9.43436 0.663547 8.09267 0.700915 6.81638 1.05057C5.5401 1.40023 4.36671 2.05191 3.39532 2.95056C2.42394 3.84921 1.68309 4.96843 1.23536 6.2137C0.787628 7.45897 0.646162 8.79371 0.822912 10.1052C0.999661 11.4166 1.48943 12.6663 2.25086 13.7486C3.01229 14.8309 4.023 15.7141 5.19764 16.3235C6.37227 16.9329 7.67632 17.2507 8.99963 17.25C9.19854 17.25 9.38931 17.171 9.52996 17.0303C9.67061 16.8897 9.74963 16.6989 9.74963 16.5C9.74963 16.3011 9.67061 16.1103 9.52996 15.9697C9.38931 15.829 9.19854 15.75 8.99963 15.75Z\" fill=\"white\"><\/path><path d=\"M11.7802 11.7802C11.9209 11.6396 11.9998 11.4489 11.9998 11.25C11.9998 11.0511 11.9209 10.8604 11.7802 10.7198L9.75 8.6895V4.5C9.75 4.30109 9.67098 4.11032 9.53033 3.96967C9.38968 3.82902 9.19891 3.75 9 3.75C8.80109 3.75 8.61032 3.82902 8.46967 3.96967C8.32902 4.11032 8.25 4.30109 8.25 4.5V9C8.25004 9.1989 8.32909 9.38963 8.46975 9.53025L10.7198 11.7802C10.8604 11.9209 11.0511 11.9998 11.25 11.9998C11.4489 11.9998 11.6396 11.9209 11.7802 11.7802Z\" fill=\"white\"><\/path><\/g><defs><clipPath id=\"clip0_505_523\"><rect width=\"18\" height=\"18\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">30 mins<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"556\" class=\"elementor elementor-556 e-loop-item e-loop-item-2153 post-2153 recipe type-recipe status-publish has-post-thumbnail hentry\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-fc23f9e e-flex e-con-boxed e-con e-parent\" data-id=\"fc23f9e\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/www.kanziapple.com\/lt\/recipe\/mazieji-kruasanai-su-obuoliais\/\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-67898cc elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"67898cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Vaikesed-ouna-sarvesaiad-1024x1024.jpg\" class=\"attachment-large size-large wp-image-2152\" alt=\"\" srcset=\"https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Vaikesed-ouna-sarvesaiad-1024x1024.jpg 1024w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Vaikesed-ouna-sarvesaiad-300x300.jpg 300w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Vaikesed-ouna-sarvesaiad-150x150.jpg 150w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Vaikesed-ouna-sarvesaiad-768x768.jpg 768w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Vaikesed-ouna-sarvesaiad-1536x1536.jpg 1536w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Vaikesed-ouna-sarvesaiad-2048x2048.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-becb9d1 e-con-full e-flex e-con e-child\" data-id=\"becb9d1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b8199d6 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"b8199d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">MA\u017dIEJI KRUASANAI SU OBUOLIAIS<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b94addd elementor-icon-list--layout-inline elementor-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b94addd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\" viewBox=\"0 0 18 18\" fill=\"none\"><g clip-path=\"url(#clip0_505_523)\"><path d=\"M15.9336 12.6309C16.3478 12.6309 16.6836 12.2951 16.6836 11.8809C16.6836 11.4666 16.3478 11.1309 15.9336 11.1309C15.5194 11.1309 15.1836 11.4666 15.1836 11.8809C15.1836 12.2951 15.5194 12.6309 15.9336 12.6309Z\" fill=\"white\"><\/path><path d=\"M14.2979 15.0469C14.7121 15.0469 15.0479 14.7111 15.0479 14.2969C15.0479 13.8827 14.7121 13.5469 14.2979 13.5469C13.8836 13.5469 13.5479 13.8827 13.5479 14.2969C13.5479 14.7111 13.8836 15.0469 14.2979 15.0469Z\" fill=\"white\"><\/path><path d=\"M16.4971 9.75391C16.9113 9.75391 17.2471 9.41812 17.2471 9.00391C17.2471 8.58969 16.9113 8.25391 16.4971 8.25391C16.0829 8.25391 15.7471 8.58969 15.7471 9.00391C15.7471 9.41812 16.0829 9.75391 16.4971 9.75391Z\" fill=\"white\"><\/path><path d=\"M11.8682 16.6855C12.2824 16.6855 12.6182 16.3498 12.6182 15.9355C12.6182 15.5213 12.2824 15.1855 11.8682 15.1855C11.454 15.1855 11.1182 15.5213 11.1182 15.9355C11.1182 16.3498 11.454 16.6855 11.8682 16.6855Z\" fill=\"white\"><\/path><path d=\"M8.99963 15.75C7.91942 15.7513 6.85467 15.4933 5.89484 14.9978C4.93501 14.5022 4.10813 13.7835 3.48367 12.9021C2.85921 12.0207 2.45541 11.0023 2.3062 9.9324C2.15699 8.86254 2.26672 7.77249 2.62618 6.75384C2.98563 5.73519 3.58432 4.81769 4.37193 4.07841C5.15954 3.33913 6.11307 2.79968 7.15242 2.50537C8.19176 2.21106 9.28656 2.17049 10.3448 2.38707C11.4031 2.60364 12.394 3.07104 13.2341 3.75H11.9996C11.8007 3.75 11.61 3.82902 11.4693 3.96967C11.3286 4.11032 11.2496 4.30109 11.2496 4.5C11.2496 4.69891 11.3286 4.88968 11.4693 5.03033C11.61 5.17098 11.8007 5.25 11.9996 5.25H14.9996C15.1985 5.25 15.3893 5.17098 15.53 5.03033C15.6706 4.88968 15.7496 4.69891 15.7496 4.5V1.5C15.7496 1.30109 15.6706 1.11032 15.53 0.96967C15.3893 0.829018 15.1985 0.75 14.9996 0.75C14.8007 0.75 14.61 0.829018 14.4693 0.96967C14.3286 1.11032 14.2496 1.30109 14.2496 1.5V2.64825C13.2297 1.80506 12.0219 1.2197 10.7281 0.941625C9.43436 0.663547 8.09267 0.700915 6.81638 1.05057C5.5401 1.40023 4.36671 2.05191 3.39532 2.95056C2.42394 3.84921 1.68309 4.96843 1.23536 6.2137C0.787628 7.45897 0.646162 8.79371 0.822912 10.1052C0.999661 11.4166 1.48943 12.6663 2.25086 13.7486C3.01229 14.8309 4.023 15.7141 5.19764 16.3235C6.37227 16.9329 7.67632 17.2507 8.99963 17.25C9.19854 17.25 9.38931 17.171 9.52996 17.0303C9.67061 16.8897 9.74963 16.6989 9.74963 16.5C9.74963 16.3011 9.67061 16.1103 9.52996 15.9697C9.38931 15.829 9.19854 15.75 8.99963 15.75Z\" fill=\"white\"><\/path><path d=\"M11.7802 11.7802C11.9209 11.6396 11.9998 11.4489 11.9998 11.25C11.9998 11.0511 11.9209 10.8604 11.7802 10.7198L9.75 8.6895V4.5C9.75 4.30109 9.67098 4.11032 9.53033 3.96967C9.38968 3.82902 9.19891 3.75 9 3.75C8.80109 3.75 8.61032 3.82902 8.46967 3.96967C8.32902 4.11032 8.25 4.30109 8.25 4.5V9C8.25004 9.1989 8.32909 9.38963 8.46975 9.53025L10.7198 11.7802C10.8604 11.9209 11.0511 11.9998 11.25 11.9998C11.4489 11.9998 11.6396 11.9209 11.7802 11.7802Z\" fill=\"white\"><\/path><\/g><defs><clipPath id=\"clip0_505_523\"><rect width=\"18\" height=\"18\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">25 mins<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"556\" class=\"elementor elementor-556 e-loop-item e-loop-item-2146 post-2146 recipe type-recipe status-publish has-post-thumbnail hentry\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a class=\"elementor-element elementor-element-fc23f9e e-flex e-con-boxed e-con e-parent\" data-id=\"fc23f9e\" data-element_type=\"container\" data-e-type=\"container\" href=\"https:\/\/www.kanziapple.com\/lt\/recipe\/skrebuciai-su-obuoliais\/\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-67898cc elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"67898cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Ouna-rostsaiad-1024x1024.jpg\" class=\"attachment-large size-large wp-image-2145\" alt=\"\" srcset=\"https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Ouna-rostsaiad-1024x1024.jpg 1024w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Ouna-rostsaiad-300x300.jpg 300w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Ouna-rostsaiad-150x150.jpg 150w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Ouna-rostsaiad-768x768.jpg 768w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Ouna-rostsaiad-1536x1536.jpg 1536w, https:\/\/www.kanziapple.com\/wp-content\/uploads\/2025\/11\/Ouna-rostsaiad-2048x2048.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-becb9d1 e-con-full e-flex e-con e-child\" data-id=\"becb9d1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b8199d6 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"b8199d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">SKREBU\u010cIAI SU OBUOLIAIS<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b94addd elementor-icon-list--layout-inline elementor-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b94addd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\" viewBox=\"0 0 18 18\" fill=\"none\"><g clip-path=\"url(#clip0_505_523)\"><path d=\"M15.9336 12.6309C16.3478 12.6309 16.6836 12.2951 16.6836 11.8809C16.6836 11.4666 16.3478 11.1309 15.9336 11.1309C15.5194 11.1309 15.1836 11.4666 15.1836 11.8809C15.1836 12.2951 15.5194 12.6309 15.9336 12.6309Z\" fill=\"white\"><\/path><path d=\"M14.2979 15.0469C14.7121 15.0469 15.0479 14.7111 15.0479 14.2969C15.0479 13.8827 14.7121 13.5469 14.2979 13.5469C13.8836 13.5469 13.5479 13.8827 13.5479 14.2969C13.5479 14.7111 13.8836 15.0469 14.2979 15.0469Z\" fill=\"white\"><\/path><path d=\"M16.4971 9.75391C16.9113 9.75391 17.2471 9.41812 17.2471 9.00391C17.2471 8.58969 16.9113 8.25391 16.4971 8.25391C16.0829 8.25391 15.7471 8.58969 15.7471 9.00391C15.7471 9.41812 16.0829 9.75391 16.4971 9.75391Z\" fill=\"white\"><\/path><path d=\"M11.8682 16.6855C12.2824 16.6855 12.6182 16.3498 12.6182 15.9355C12.6182 15.5213 12.2824 15.1855 11.8682 15.1855C11.454 15.1855 11.1182 15.5213 11.1182 15.9355C11.1182 16.3498 11.454 16.6855 11.8682 16.6855Z\" fill=\"white\"><\/path><path d=\"M8.99963 15.75C7.91942 15.7513 6.85467 15.4933 5.89484 14.9978C4.93501 14.5022 4.10813 13.7835 3.48367 12.9021C2.85921 12.0207 2.45541 11.0023 2.3062 9.9324C2.15699 8.86254 2.26672 7.77249 2.62618 6.75384C2.98563 5.73519 3.58432 4.81769 4.37193 4.07841C5.15954 3.33913 6.11307 2.79968 7.15242 2.50537C8.19176 2.21106 9.28656 2.17049 10.3448 2.38707C11.4031 2.60364 12.394 3.07104 13.2341 3.75H11.9996C11.8007 3.75 11.61 3.82902 11.4693 3.96967C11.3286 4.11032 11.2496 4.30109 11.2496 4.5C11.2496 4.69891 11.3286 4.88968 11.4693 5.03033C11.61 5.17098 11.8007 5.25 11.9996 5.25H14.9996C15.1985 5.25 15.3893 5.17098 15.53 5.03033C15.6706 4.88968 15.7496 4.69891 15.7496 4.5V1.5C15.7496 1.30109 15.6706 1.11032 15.53 0.96967C15.3893 0.829018 15.1985 0.75 14.9996 0.75C14.8007 0.75 14.61 0.829018 14.4693 0.96967C14.3286 1.11032 14.2496 1.30109 14.2496 1.5V2.64825C13.2297 1.80506 12.0219 1.2197 10.7281 0.941625C9.43436 0.663547 8.09267 0.700915 6.81638 1.05057C5.5401 1.40023 4.36671 2.05191 3.39532 2.95056C2.42394 3.84921 1.68309 4.96843 1.23536 6.2137C0.787628 7.45897 0.646162 8.79371 0.822912 10.1052C0.999661 11.4166 1.48943 12.6663 2.25086 13.7486C3.01229 14.8309 4.023 15.7141 5.19764 16.3235C6.37227 16.9329 7.67632 17.2507 8.99963 17.25C9.19854 17.25 9.38931 17.171 9.52996 17.0303C9.67061 16.8897 9.74963 16.6989 9.74963 16.5C9.74963 16.3011 9.67061 16.1103 9.52996 15.9697C9.38931 15.829 9.19854 15.75 8.99963 15.75Z\" fill=\"white\"><\/path><path d=\"M11.7802 11.7802C11.9209 11.6396 11.9998 11.4489 11.9998 11.25C11.9998 11.0511 11.9209 10.8604 11.7802 10.7198L9.75 8.6895V4.5C9.75 4.30109 9.67098 4.11032 9.53033 3.96967C9.38968 3.82902 9.19891 3.75 9 3.75C8.80109 3.75 8.61032 3.82902 8.46967 3.96967C8.32902 4.11032 8.25 4.30109 8.25 4.5V9C8.25004 9.1989 8.32909 9.38963 8.46975 9.53025L10.7198 11.7802C10.8604 11.9209 11.0511 11.9998 11.25 11.9998C11.4489 11.9998 11.6396 11.9209 11.7802 11.7802Z\" fill=\"white\"><\/path><\/g><defs><clipPath id=\"clip0_505_523\"><rect width=\"18\" height=\"18\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">10 mins<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<span class=\"e-load-more-spinner\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-spinner\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M304 48c0 26.51-21.49 48-48 48s-48-21.49-48-48 21.49-48 48-48 48 21.49 48 48zm-48 368c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.49-48-48-48zm208-208c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.49-48-48-48zM96 256c0-26.51-21.49-48-48-48S0 229.49 0 256s21.49 48 48 48 48-21.49 48-48zm12.922 99.078c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48c0-26.509-21.491-48-48-48zm294.156 0c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48c0-26.509-21.49-48-48-48zM108.922 60.922c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.491-48-48-48z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\n\t\t\t\t<div class=\"e-load-more-anchor\" data-page=\"1\" data-max-page=\"2\" data-next-page=\"https:\/\/www.kanziapple.com\/lt\/wp-json\/wp\/v2\/pages\/2011\/page\/2\/\"><\/div>\n\t\t\t\t<div class=\"e-load-more-message\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eddb65a e-con-full e-flex e-con e-child\" data-id=\"eddb65a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dd05fd7 elementor-widget elementor-widget-heading\" data-id=\"dd05fd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">ATRASKITE M\u016aS\u0172 KANZI RECEPT\u0172 ARCHYV\u0104 YOUTUBE<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-453d84e elementor-align-justify elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"453d84e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.youtube.com\/@kanzi9915\/playlists\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">APSILANKYKITE YOUTUBE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Skanu. \u0160vie\u017eia. Ir suteikia j\u0117g\u0173. KANZI\u00ae receptai \u2013 tai dr\u0105s\u016bs skoni\u0173 deriniai be r\u016bpes\u010di\u0173. Greita, \u0161vie\u017eia ir gardu \u2013 sukurta j\u016bs\u0173 dienai. J\u0116G\u0172 SUTEIKIANTYS RECEPTAI KANZI\u00ae sezonas su m\u016bs\u0173 kruop\u0161\u010diai atrinktais receptais \u2013 saldu, gaivu, visada tra\u0161ku. Nuo greit\u0173 u\u017ekand\u017ei\u0173 iki i\u0161skirtini\u0173 patiekal\u0173 \u2013 id\u0117jos, kurios tiks j\u016bs\u0173 dienai ir nustebins skoniu. Receptus nuolat papildome. [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"class_list":["post-2011","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.kanziapple.com\/lt\/wp-json\/wp\/v2\/pages\/2011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kanziapple.com\/lt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.kanziapple.com\/lt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.kanziapple.com\/lt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kanziapple.com\/lt\/wp-json\/wp\/v2\/comments?post=2011"}],"version-history":[{"count":1,"href":"https:\/\/www.kanziapple.com\/lt\/wp-json\/wp\/v2\/pages\/2011\/revisions"}],"predecessor-version":[{"id":2012,"href":"https:\/\/www.kanziapple.com\/lt\/wp-json\/wp\/v2\/pages\/2011\/revisions\/2012"}],"wp:attachment":[{"href":"https:\/\/www.kanziapple.com\/lt\/wp-json\/wp\/v2\/media?parent=2011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}